{"id":12285,"date":"2024-03-24T21:34:56","date_gmt":"2024-03-24T20:34:56","guid":{"rendered":"https:\/\/www.eco-sistemi.net\/wp-content\/uploads\/2024\/03\/Catalogo-Listino-PE-CAV-2024.pdf"},"modified":"2024-03-24T21:34:56","modified_gmt":"2024-03-24T20:34:56","slug":"catalogo-listino-pe-cav-2024","status":"inherit","type":"attachment","link":"https:\/\/www.eco-sistemi.net\/fr\/catalogo-listino-pe-cav-2024\/","title":{"rendered":"Catalogo Listino PE CAV 2024"},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"class_list":["post-12285","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.eco-sistemi.net\/wp-content\/uploads\/2024\/03\/Catalogo-Listino-PE-CAV-2024.pdf'><img loading=\"lazy\" decoding=\"async\" width=\"212\" height=\"300\" src=\"https:\/\/www.eco-sistemi.net\/wp-content\/uploads\/2024\/03\/Catalogo-Listino-PE-CAV-2024-pdf-212x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"file","mime_type":"application\/pdf","media_details":{"sizes":{"full":{"file":"Catalogo-Listino-PE-CAV-2024-pdf.jpg","width":1058,"height":1497,"mime_type":"application\/pdf","source_url":"https:\/\/www.eco-sistemi.net\/wp-content\/uploads\/2024\/03\/Catalogo-Listino-PE-CAV-2024-pdf.jpg"},"medium":{"file":"Catalogo-Listino-PE-CAV-2024-pdf-212x300.jpg","width":212,"height":300,"filesize":24277,"mime_type":"image\/jpeg","source_url":"https:\/\/www.eco-sistemi.net\/wp-content\/uploads\/2024\/03\/Catalogo-Listino-PE-CAV-2024-pdf-212x300.jpg"},"large":{"file":"Catalogo-Listino-PE-CAV-2024-pdf-724x1024.jpg","width":724,"height":1024,"filesize":160786,"mime_type":"image\/jpeg","source_url":"https:\/\/www.eco-sistemi.net\/wp-content\/uploads\/2024\/03\/Catalogo-Listino-PE-CAV-2024-pdf-724x1024.jpg"},"thumbnail":{"file":"Catalogo-Listino-PE-CAV-2024-pdf-106x150.jpg","width":106,"height":150,"filesize":10818,"mime_type":"image\/jpeg","source_url":"https:\/\/www.eco-sistemi.net\/wp-content\/uploads\/2024\/03\/Catalogo-Listino-PE-CAV-2024-pdf-106x150.jpg"}},"filesize":2251395},"post":null,"source_url":"https:\/\/www.eco-sistemi.net\/wp-content\/uploads\/2024\/03\/Catalogo-Listino-PE-CAV-2024.pdf","filename":"Catalogo-Listino-PE-CAV-2024.pdf","filesize":2251395,"_links":{"self":[{"href":"https:\/\/www.eco-sistemi.net\/fr\/wp-json\/wp\/v2\/media\/12285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eco-sistemi.net\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.eco-sistemi.net\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.eco-sistemi.net\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eco-sistemi.net\/fr\/wp-json\/wp\/v2\/comments?post=12285"}]}}