{"id":3,"date":"2021-12-29T21:38:56","date_gmt":"2021-12-29T21:38:56","guid":{"rendered":"https:\/\/www.eco-sistemi.net\/?page_id=3"},"modified":"2024-01-30T14:15:31","modified_gmt":"2024-01-30T13:15:31","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/www.eco-sistemi.net\/en\/privacy-policy\/","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Features CTA Section&#8221; _builder_version=&#8221;4.9.10&#8243; background_color=&#8221;#FFFFFF&#8221; custom_padding=&#8221;100px|0px|100px|0px&#8221; bottom_divider_style=&#8221;slant&#8221; bottom_divider_color=&#8221;#3c3d41&#8243; bottom_divider_flip=&#8221;horizontal&#8221; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;Right Sided Image&#8221; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;60px|0px|60px|0px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text content_tablet=&#8221;&#8221; content_phone=&#8221;&#8221; content_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat|300|||||||&#8221; text_text_color=&#8221;#009de0&#8243; text_font_size=&#8221;40px&#8221; header_text_color=&#8221;#0C71C3&#8243; custom_margin=&#8221;||30px||false|false&#8221; text_line_height_tablet=&#8221;&#8221; text_line_height_phone=&#8221;1.1em&#8221; text_line_height_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3 style=\"text-align: left;\" align=\"center\"><span style=\"color: #00ccff;\"><strong>Informativa sul trattamento dei dati personali ai sensi dell\u2019art. 13 del D. Lgs. n. 196\/03<\/strong><\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text content_tablet=&#8221;&#8221; content_phone=&#8221;&#8221; content_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat|300|||||||&#8221; text_text_color=&#8221;rgba(0,0,0,0.66)&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; text_font_size_tablet=&#8221;&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div id=\"contenitorecs\">\n<div id=\"contenutocs\">\n<p align=\"justify\">Eco Sistemi S.r.l. in qualit\u00e0 di Titolare del Trattamento rende a tutti gli utenti dell\u2019Area operatori l\u2019informativa sul trattamento dei dati personali, garantendo che il medesimo si svolge nel rispetto dei diritti, delle libert\u00e0 fondamentali, nonch\u00e9 della dignit\u00e0 delle persone con particolare riferimento alla riservatezza e all\u2019identit\u00e0 personale. Pertanto, secondo quanto disposto dall\u2019art. 13 del D.Lgs. n. 196\/03, Vi forniamo le seguenti informazioni:<\/p>\n<p align=\"justify\"><strong>Finalit\u00e0 del trattamento<\/strong>\u00a0I Vostri dati verranno trattati in relazione alla necessit\u00e0 di invio del materiale richiesto. Il trattamento dei dati avverr\u00e0 mediante l\u2019utilizzo di strumenti e procedure idonei a garantirne la sicurezza e la riservatezza e potr\u00e0 essere effettuato attraverso l\u2019ausilio di strumenti elettronici.<\/p>\n<p align=\"justify\"><strong>Obbligo o facolt\u00e0 di conferire i dati e conseguenze dell\u2019eventuale rifiuto<\/strong>\u00a0Per quanto concerne i dati che siamo obbligati a conoscere, al fine di adempiere alle finalit\u00e0 suddette, il loro mancato conferimento da parte Vostra comporter\u00e0 l\u2019impossibilit\u00e0 di instaurare o proseguire il rapporto, nei limiti in cui tali dati sono necessari all\u2019esecuzione dello stesso. Per quanto riguarda i dati che non siamo obbligati a conoscere, il loro mancato ottenimento sar\u00e0 da noi valutato di volta in volta, e determiner\u00e0 le conseguenti decisioni rapportate all\u2019importanza per noi dei dati richiesti e da Voi non conferitici.<\/p>\n<p align=\"justify\"><strong>Comunicazione e diffusione<\/strong>\u00a0I Vostri dati non verranno da noi \u201cdiffusi\u201d, con tale termine intendendosi il darne conoscenza a soggetti indeterminati in qualunque modo, anche mediante la loro messa a disposizione o consultazione. I Vostri dati potranno invece essere da noi \u201ccomunicati\u201d, con tale termine intendendosi il darne conoscenza ad uno o pi\u00f9 soggetti determinati, nei seguenti termini: a soggetti incaricati con le modalit\u00e0 previste dalla normativa, all\u2019interno della nostra organizzazione di trattare i Vostri dati; a soggetti che possono accedere ai dati in forza di disposizione di legge, di regolamento o di normativa comunitaria, nei limiti previsti da tali norme.<\/p>\n<p align=\"justify\"><strong>I Vostri diritti<\/strong>\u00a0L\u2019interessato ha il diritto in qualunque momento di ottenere la conferma dell\u2019esistenza o meno dei medesimi dati e di conoscerne il contenuto e l\u2019origine, verificarne l\u2019esattezza, o chiederne l\u2019integrazione o l\u2019aggiornamento, oppure la rettificazione (art. 7 D. Lgs. n. 196\/03). Ai sensi del medesimo articolo si ha il diritto di chiedere la cancellazione, la trasformazione in forma anonima o il blocco dei dati trattati in violazione della legge, nonch\u00e9 di opporsi in ogni caso, per motivi legittimi, al loro trattamento. Per esercitare tali diritti Vi potrete rivolgere al Titolare del trattamento, reperibile ai recapiti riportati nell\u2019intestazione della presente.<\/p>\n<p align=\"justify\"><strong>Titolari e Responsabili dei trattamenti<\/strong> L\u2019elenco degli eventuali responsabili nominati pu\u00f2 essere consultato facendone richiesta presso i nostri uffici. Il Titolare del Trattamento dei Vostri dati personali \u00e8 Eco Sistemi S.r.l. con sede legale in Via Val Tiberina 79 &#8211; 63074 San Benedetto del Tronto AP.<\/p>\n<\/div>\n<\/div>\n<div id=\"footer\">\n<div id=\"infooter\">\n<div class=\"footinterno\"><\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Section&#8221; _builder_version=&#8221;3.22&#8243; background_color=&#8221;#3c3d41&#8243; custom_padding=&#8221;0px||0px|&#8221; custom_padding_tablet=&#8221;0px||0px|&#8221; transparent_background=&#8221;off&#8221; padding_mobile=&#8221;on&#8221; make_fullwidth=&#8221;off&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;on&#8221; global_module=&#8221;11834&#8243; saved_tabs=&#8221;all&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_5,1_5,1_5,1_5,1_5&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; padding_mobile=&#8221;on&#8221; column_padding_mobile=&#8221;on&#8221; admin_label=&#8221;Row&#8221; _builder_version=&#8221;3.25&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_padding=&#8221;50px||50px|&#8221; make_fullwidth=&#8221;off&#8221; use_custom_width=&#8221;off&#8221; width_unit=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.9.10&#8243; text_font=&#8221;Source Sans Pro|on|||&#8221; text_text_color=&#8221;#0e91ef&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.4em&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;||8px|&#8221; hover_enabled=&#8221;0&#8243; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Eco Sistemi <span>S.r.l.<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.9.10&#8243; text_font=&#8221;Montserrat|500|||||||&#8221; text_text_color=&#8221;#ffffff&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_padding=&#8221;0px|||&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Via dell&#8217;Aspo, 7A<br \/>63100 Ascoli Piceno (AP)<br \/>P.IVA 02170540443<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.9.4&#8243; text_font=&#8221;Source Sans Pro|on|||&#8221; text_text_color=&#8221;#0e91ef&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.4em&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;||8px|&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221;]Contatti[\/et_pb_text][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.9.10&#8243; text_font=&#8221;Montserrat|500|||||||&#8221; text_text_color=&#8221;#ffffff&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_padding=&#8221;0px|||&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Cell. 324 8621967<br \/>Tel. 0736 317974<br \/><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"mailto:info@eco-sistemi.net\">info@eco-sistemi.net<\/a><\/span><br \/><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"mailto:eco-sistemi@pec.eco-sistemi.net\">Pec<\/a><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.10.2&#8243; text_font=&#8221;Source Sans Pro|on|||&#8221; text_text_color=&#8221;#0e91ef&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.4em&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;||8px|&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221;]Documenti[\/et_pb_text][et_pb_text _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat|500|||||||&#8221; text_font_size=&#8221;15px&#8221; text_line_height=&#8221;1.8em&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"\/privacy-policy\/\"><span style=\"color: #ffffff;\">Informativa sulla Privacy<\/span><\/a><br \/><span style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"\/condizioni-di-vendita\/\">Condizioni generali di vendita<\/a><\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.10.2&#8243; text_font=&#8221;Source Sans Pro|on|||&#8221; text_text_color=&#8221;#0e91ef&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.4em&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;||8px|&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221;]Seguici[\/et_pb_text][et_pb_social_media_follow admin_label=&#8221;Social Media Follow&#8221; _builder_version=&#8221;4.10.2&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|100%|100%|100%|100%&#8221; link_shape=&#8221;circle&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/eco.sistemi.snc\/&#8221; _builder_version=&#8221;4.10.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#3b5998&#8243; bg_color=&#8221;#3b5998&#8243; global_colors_info=&#8221;{}&#8221; link_shape=&#8221;circle&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; _builder_version=&#8221;4.10.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#ea2c59&#8243; bg_color=&#8221;#00aced&#8221; global_colors_info=&#8221;{}&#8221; link_shape=&#8221;circle&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;twitter&#8221; _builder_version=&#8221;4.10.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#00aced&#8221; bg_color=&#8221;#dd4b39&#8243; global_colors_info=&#8221;{}&#8221; link_shape=&#8221;circle&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]twitter[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;linkedin&#8221; url=&#8221;https:\/\/it.linkedin.com\/company\/eco-sistemi-snc&#8221; _builder_version=&#8221;4.10.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#007bb6&#8243; bg_color=&#8221;#cb2027&#8243; global_colors_info=&#8221;{}&#8221; link_shape=&#8221;circle&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]linkedin[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.10.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.10.2&#8243; text_font=&#8221;Source Sans Pro|on|||&#8221; text_text_color=&#8221;#0e91ef&#8221; text_font_size=&#8221;18px&#8221; text_line_height=&#8221;1.4em&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; custom_margin=&#8221;||8px|&#8221; use_border_color=&#8221;off&#8221; border_color=&#8221;#ffffff&#8221; border_style=&#8221;solid&#8221; global_colors_info=&#8221;{}&#8221;]Official Partner[\/et_pb_text][et_pb_image src=&#8221;https:\/\/www.eco-sistemi.net\/wp-content\/uploads\/2021\/12\/logo-ascoli.png&#8221; title_text=&#8221;logo-ascoli&#8221; url_new_window=&#8221;on&#8221; _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; transform_scale=&#8221;86%|86%&#8221; transform_translate=&#8221;-21px|4px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informativa sul trattamento dei dati personali ai sensi dell\u2019art. 13 del D. Lgs. n. 196\/03 Eco Sistemi S.r.l. in qualit\u00e0 di Titolare del Trattamento rende a tutti gli utenti dell\u2019Area operatori l\u2019informativa sul trattamento dei dati personali, garantendo che il medesimo si svolge nel rispetto dei diritti, delle libert\u00e0 fondamentali, nonch\u00e9 della dignit\u00e0 delle persone [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:heading -->\n<h2>Who we are<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>Our website address is: https:\/\/www.eco-sistemi.net.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>Comments<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>When visitors leave comments on the site we collect the data shown in the comments form, and also the visitor\u2019s IP address and browser user agent string to help spam detection.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>An anonymized string created from your email address (also called a hash) may be provided to the Gravatar service to see if you are using it. The Gravatar service privacy policy is available here: https:\/\/automattic.com\/privacy\/. After approval of your comment, your profile picture is visible to the public in the context of your comment.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>Media<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>If you upload images to the website, you should avoid uploading images with embedded location data (EXIF GPS) included. Visitors to the website can download and extract any location data from images on the website.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>Cookies<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>If you leave a comment on our site you may opt-in to saving your name, email address and website in cookies. These are for your convenience so that you do not have to fill in your details again when you leave another comment. These cookies will last for one year.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>If you visit our login page, we will set a temporary cookie to determine if your browser accepts cookies. This cookie contains no personal data and is discarded when you close your browser.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>When you log in, we will also set up several cookies to save your login information and your screen display choices. Login cookies last for two days, and screen options cookies last for a year. If you select \"Remember Me\", your login will persist for two weeks. If you log out of your account, the login cookies will be removed.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>If you edit or publish an article, an additional cookie will be saved in your browser. This cookie includes no personal data and simply indicates the post ID of the article you just edited. It expires after 1 day.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>Embedded content from other websites<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>Articles on this site may include embedded content (e.g. videos, images, articles, etc.). Embedded content from other websites behaves in the exact same way as if the visitor has visited the other website.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>These websites may collect data about you, use cookies, embed additional third-party tracking, and monitor your interaction with that embedded content, including tracking your interaction with the embedded content if you have an account and are logged in to that website.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>Who we share your data with<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>If you request a password reset, your IP address will be included in the reset email.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>How long we retain your data<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>If you leave a comment, the comment and its metadata are retained indefinitely. This is so we can recognize and approve any follow-up comments automatically instead of holding them in a moderation queue.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>For users that register on our website (if any), we also store the personal information they provide in their user profile. All users can see, edit, or delete their personal information at any time (except they cannot change their username). Website administrators can also see and edit that information.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>What rights you have over your data<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>If you have an account on this site, or have left comments, you can request to receive an exported file of the personal data we hold about you, including any data you have provided to us. You can also request that we erase any personal data we hold about you. This does not include any data we are obliged to keep for administrative, legal, or security purposes.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading -->\n<h2>Where we send your data<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph -->\n<p><strong class=\"privacy-policy-tutorial\">Suggested text: <\/strong>Visitor comments may be checked through an automated spam detection service.<\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":"","footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.eco-sistemi.net\/en\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eco-sistemi.net\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.eco-sistemi.net\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.eco-sistemi.net\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eco-sistemi.net\/en\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":9,"href":"https:\/\/www.eco-sistemi.net\/en\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":12250,"href":"https:\/\/www.eco-sistemi.net\/en\/wp-json\/wp\/v2\/pages\/3\/revisions\/12250"}],"wp:attachment":[{"href":"https:\/\/www.eco-sistemi.net\/en\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}